{"id":233,"count":1,"description":"","link":"https:\/\/live-french.net\/ru\/blog\/tag\/%d0%bf%d0%b5%d1%80%d0%b5%d0%bc%d0%b5%d1%89%d0%b5%d0%bd%d0%b8%d0%b5\/","name":"\u043f\u0435\u0440\u0435\u043c\u0435\u0449\u0435\u043d\u0438\u0435","slug":"%d0%bf%d0%b5%d1%80%d0%b5%d0%bc%d0%b5%d1%89%d0%b5%d0%bd%d0%b8%d0%b5","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u043f\u0435\u0440\u0435\u043c\u0435\u0449\u0435\u043d\u0438\u0435 Archives | Live French<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/live-french.net\/ru\/blog\/tag\/%d0%bf%d0%b5%d1%80%d0%b5%d0%bc%d0%b5%d1%89%d0%b5%d0%bd%d0%b8%d0%b5\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u043f\u0435\u0440\u0435\u043c\u0435\u0449\u0435\u043d\u0438\u0435 Archives | Live French\" \/>\n<meta property=\"og:url\" content=\"https:\/\/live-french.net\/ru\/blog\/tag\/%d0%bf%d0%b5%d1%80%d0%b5%d0%bc%d0%b5%d1%89%d0%b5%d0%bd%d0%b8%d0%b5\/\" \/>\n<meta property=\"og:site_name\" content=\"Live French\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/live-french.net\\\/ru\\\/blog\\\/tag\\\/%d0%bf%d0%b5%d1%80%d0%b5%d0%bc%d0%b5%d1%89%d0%b5%d0%bd%d0%b8%d0%b5\\\/\",\"url\":\"https:\\\/\\\/live-french.net\\\/ru\\\/blog\\\/tag\\\/%d0%bf%d0%b5%d1%80%d0%b5%d0%bc%d0%b5%d1%89%d0%b5%d0%bd%d0%b8%d0%b5\\\/\",\"name\":\"\u043f\u0435\u0440\u0435\u043c\u0435\u0449\u0435\u043d\u0438\u0435 Archives | Live French\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/live-french.net\\\/ru\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/live-french.net\\\/ru\\\/blog\\\/tag\\\/%d0%bf%d0%b5%d1%80%d0%b5%d0%bc%d0%b5%d1%89%d0%b5%d0%bd%d0%b8%d0%b5\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/live-french.net\\\/ru\\\/blog\\\/tag\\\/%d0%bf%d0%b5%d1%80%d0%b5%d0%bc%d0%b5%d1%89%d0%b5%d0%bd%d0%b8%d0%b5\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/live-french.net\\\/ru\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u043f\u0435\u0440\u0435\u043c\u0435\u0449\u0435\u043d\u0438\u0435\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/live-french.net\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/live-french.net\\\/ru\\\/\",\"name\":\"Live French\",\"description\":\"Learn French Online\",\"publisher\":{\"@id\":\"https:\\\/\\\/live-french.net\\\/ru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/live-french.net\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/live-french.net\\\/ru\\\/#organization\",\"name\":\"Live French\",\"url\":\"https:\\\/\\\/live-french.net\\\/ru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/live-french.net\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/live-french.net\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/cropped-LiveFrenchLogo.png\",\"contentUrl\":\"https:\\\/\\\/live-french.net\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/cropped-LiveFrenchLogo.png\",\"width\":3319,\"height\":593,\"caption\":\"Live French\"},\"image\":{\"@id\":\"https:\\\/\\\/live-french.net\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u043f\u0435\u0440\u0435\u043c\u0435\u0449\u0435\u043d\u0438\u0435 Archives | Live French","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/live-french.net\/ru\/blog\/tag\/%d0%bf%d0%b5%d1%80%d0%b5%d0%bc%d0%b5%d1%89%d0%b5%d0%bd%d0%b8%d0%b5\/","og_locale":"ru_RU","og_type":"article","og_title":"\u043f\u0435\u0440\u0435\u043c\u0435\u0449\u0435\u043d\u0438\u0435 Archives | Live French","og_url":"https:\/\/live-french.net\/ru\/blog\/tag\/%d0%bf%d0%b5%d1%80%d0%b5%d0%bc%d0%b5%d1%89%d0%b5%d0%bd%d0%b8%d0%b5\/","og_site_name":"Live French","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/live-french.net\/ru\/blog\/tag\/%d0%bf%d0%b5%d1%80%d0%b5%d0%bc%d0%b5%d1%89%d0%b5%d0%bd%d0%b8%d0%b5\/","url":"https:\/\/live-french.net\/ru\/blog\/tag\/%d0%bf%d0%b5%d1%80%d0%b5%d0%bc%d0%b5%d1%89%d0%b5%d0%bd%d0%b8%d0%b5\/","name":"\u043f\u0435\u0440\u0435\u043c\u0435\u0449\u0435\u043d\u0438\u0435 Archives | Live French","isPartOf":{"@id":"https:\/\/live-french.net\/ru\/#website"},"breadcrumb":{"@id":"https:\/\/live-french.net\/ru\/blog\/tag\/%d0%bf%d0%b5%d1%80%d0%b5%d0%bc%d0%b5%d1%89%d0%b5%d0%bd%d0%b8%d0%b5\/#breadcrumb"},"inLanguage":"ru-RU"},{"@type":"BreadcrumbList","@id":"https:\/\/live-french.net\/ru\/blog\/tag\/%d0%bf%d0%b5%d1%80%d0%b5%d0%bc%d0%b5%d1%89%d0%b5%d0%bd%d0%b8%d0%b5\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/live-french.net\/ru\/"},{"@type":"ListItem","position":2,"name":"\u043f\u0435\u0440\u0435\u043c\u0435\u0449\u0435\u043d\u0438\u0435"}]},{"@type":"WebSite","@id":"https:\/\/live-french.net\/ru\/#website","url":"https:\/\/live-french.net\/ru\/","name":"Live French","description":"Learn French Online","publisher":{"@id":"https:\/\/live-french.net\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/live-french.net\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/live-french.net\/ru\/#organization","name":"Live French","url":"https:\/\/live-french.net\/ru\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/live-french.net\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/live-french.net\/wp-content\/uploads\/2021\/12\/cropped-LiveFrenchLogo.png","contentUrl":"https:\/\/live-french.net\/wp-content\/uploads\/2021\/12\/cropped-LiveFrenchLogo.png","width":3319,"height":593,"caption":"Live French"},"image":{"@id":"https:\/\/live-french.net\/ru\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/live-french.net\/ru\/wp-json\/wp\/v2\/tags\/233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/live-french.net\/ru\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/live-french.net\/ru\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/live-french.net\/ru\/wp-json\/wp\/v2\/posts?tags=233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}