{"id":189,"count":4,"description":"","link":"https:\/\/live-french.net\/it\/blog\/tag\/delf-it\/","name":"DELF","slug":"delf-it","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DELF Archives | Live French<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/live-french.net\/it\/blog\/tag\/delf-it\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DELF Archives | Live French\" \/>\n<meta property=\"og:url\" content=\"https:\/\/live-french.net\/it\/blog\/tag\/delf-it\/\" \/>\n<meta property=\"og:site_name\" content=\"Live French\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/live-french.net\\\/it\\\/blog\\\/tag\\\/delf-it\\\/\",\"url\":\"https:\\\/\\\/live-french.net\\\/it\\\/blog\\\/tag\\\/delf-it\\\/\",\"name\":\"DELF Archives | Live French\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/live-french.net\\\/it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/live-french.net\\\/it\\\/blog\\\/tag\\\/delf-it\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/live-french.net\\\/it\\\/blog\\\/tag\\\/delf-it\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/live-french.net\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DELF\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/live-french.net\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/live-french.net\\\/it\\\/\",\"name\":\"Live French\",\"description\":\"Learn French Online\",\"publisher\":{\"@id\":\"https:\\\/\\\/live-french.net\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/live-french.net\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/live-french.net\\\/it\\\/#organization\",\"name\":\"Live French\",\"url\":\"https:\\\/\\\/live-french.net\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/live-french.net\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/live-french.net\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/cropped-LiveFrenchLogo.png\",\"contentUrl\":\"https:\\\/\\\/live-french.net\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/cropped-LiveFrenchLogo.png\",\"width\":3319,\"height\":593,\"caption\":\"Live French\"},\"image\":{\"@id\":\"https:\\\/\\\/live-french.net\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DELF Archives | Live French","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/live-french.net\/it\/blog\/tag\/delf-it\/","og_locale":"it_IT","og_type":"article","og_title":"DELF Archives | Live French","og_url":"https:\/\/live-french.net\/it\/blog\/tag\/delf-it\/","og_site_name":"Live French","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/live-french.net\/it\/blog\/tag\/delf-it\/","url":"https:\/\/live-french.net\/it\/blog\/tag\/delf-it\/","name":"DELF Archives | Live French","isPartOf":{"@id":"https:\/\/live-french.net\/it\/#website"},"breadcrumb":{"@id":"https:\/\/live-french.net\/it\/blog\/tag\/delf-it\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/live-french.net\/it\/blog\/tag\/delf-it\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/live-french.net\/it\/"},{"@type":"ListItem","position":2,"name":"DELF"}]},{"@type":"WebSite","@id":"https:\/\/live-french.net\/it\/#website","url":"https:\/\/live-french.net\/it\/","name":"Live French","description":"Learn French Online","publisher":{"@id":"https:\/\/live-french.net\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/live-french.net\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/live-french.net\/it\/#organization","name":"Live French","url":"https:\/\/live-french.net\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/live-french.net\/it\/#\/schema\/logo\/image\/","url":"https:\/\/live-french.net\/wp-content\/uploads\/2021\/12\/cropped-LiveFrenchLogo.png","contentUrl":"https:\/\/live-french.net\/wp-content\/uploads\/2021\/12\/cropped-LiveFrenchLogo.png","width":3319,"height":593,"caption":"Live French"},"image":{"@id":"https:\/\/live-french.net\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/live-french.net\/it\/wp-json\/wp\/v2\/tags\/189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/live-french.net\/it\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/live-french.net\/it\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/live-french.net\/it\/wp-json\/wp\/v2\/posts?tags=189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}