{"id":1538,"date":"2017-10-30T23:00:27","date_gmt":"2017-10-30T22:00:27","guid":{"rendered":"https:\/\/live-french.net\/blog\/unkategorisiert\/fehler-die-sie-in-einem-bewerbungsgesprach-auf-franzosisch-vermeiden-sollten\/"},"modified":"2023-12-20T13:18:21","modified_gmt":"2023-12-20T12:18:21","slug":"bewerbungsgesprach-auf-franzosisch-2","status":"publish","type":"post","link":"https:\/\/live-french.net\/de\/blog\/business-franzoesisch\/bewerbungsgesprach-auf-franzosisch-2\/","title":{"rendered":"Fehler, die Sie in einem Bewerbungsgespr\u00e4ch auf Franz\u00f6sisch vermeiden sollten"},"content":{"rendered":"<p>Hier bei Live-French.net wissen wir wie schwierig es sein kann ein Bewerbungsgespr\u00e4ch auf Franz\u00f6sisch zu haben. Was auf anderen Sprachen passiert, das geschieht auch auf Franz\u00f6sisch, Bewerbungsgespr\u00e4che sind f\u00fcr jeden eine sehr stre\u00dfreiche Zeit.<\/p>\n<p>Die meiste Zeit sind wir uns unserer Fehler nicht bewusst. Es ist ein schreckliches Gef\u00fchl zu realisieren, dass wir uns deutlich besser schlagen k\u00f6nnten, sobald das Bewerbungsgespr\u00e4ch vorbei ist.<\/p>\n<p>Gl\u00fccklicherweise k\u00f6nnen wir einige der h\u00e4ufigsten Fehler in Bewerbungsgespr\u00e4chen auf Franz\u00f6sisch auflisten und Ihnen einige Ratschl\u00e4ge geben, wie Sie diese auf alle F\u00e4lle vermeiden k\u00f6nnen.<br \/>\nWir wissen, wie schwierig es sein kann eine herausragende Leistung im Bewerbungsgespr\u00e4ch zu zeigen, insbesondere, wenn:<\/p>\n<ul>\n<li>Die Stelle sehr gut ist und Sie sie auf jeden Fall haben m\u00f6chten<\/li>\n<li>Sie sehr nerv\u00f6s sind<\/li>\n<li><strong>Franz\u00f6sisch nicht Ihre Muttersprache ist<\/strong><\/li>\n<\/ul>\n<p>Wie auch immer, wenn Sie f\u00fcr die folgenden Fehler ein Auge offen halten, dann werden Sie auf Ihrem Weg zum Erfolg in Bewerbungsgespr\u00e4chen auf Franz\u00f6sisch einen Vorteil haben.<br \/>\n<div id=\"custom_html-26\" class=\"widget_text si-sidebar-widget si-widget si-entry widget widget_custom_html amr_widget\"><div class=\"textwidget custom-html-widget\"><a href=\"https:\/\/member.booknstart.com\/trial-registration?lg=fr&referred_by=sCTA&office_id=6\" target=\"_blank\"><img decoding=\"async\" alt=\"Cours d'essai de fran\u00e7ais\" src=\"https:\/\/live-french.net\/wp-content\/uploads\/2023\/02\/sCTA-fr.jpg\"><\/a><\/div><\/div><\/p>\n<h2>1 \u2013Einen schwachen ersten Eindruck machen<\/h2>\n<p>Einen schwachen ersten Eindruck zu machen ist einer der h\u00e4ufigsten Fehler, den Leute in Bewerbungsgespr\u00e4chen machen. Haupts\u00e4chlich weil sie vor einem oder mehreren Fremden so nerv\u00f6s werden. In Wahrheit ist es eine Herausforderung in einer solch unangenehmen Situation seine Gedanken zusammen zu halten.<br \/>\nNichtsdestotrotz k\u00f6nnen Sie einige Tipps im Kopf behalten, sodass Ihre Worte so nat\u00fcrlich und professionell wie m\u00f6glich wirken:<\/p>\n<ul>\n<li>Dies ist die perfekte Gelegenheit sich selbstsicher \u00fcber alle Anstrengungen zu f\u00fchlen, die Sie dorthin gebracht haben, wo Sie heute stehen. F\u00fchlen Sie sich stolz \u00fcber alles, das Sie wissen und die Erfahrungen, die Sie zu diesem Wissen verholfen haben.<\/li>\n<li>Halten Sie so viel Blickkontakt wie Sie k\u00f6nnen. Die Idee ist nicht wie ein Psychopath auszusehen, aber Blickkontakt wird Sie vor Ihrem potentiellen Arbeitgeber selbstsicherer erscheinen lassen<\/li>\n<li>\u00dcbung ist der Schl\u00fcssel zu einer bemerkenswerten Leistung in Ihrem Bewerbungsgespr\u00e4ch auf Franz\u00f6sisch<\/li>\n<\/ul>\n<p>Sie sollten stets ein L\u00e4cheln im Gesicht haben, um einladend zu wirken und bereit sein jede Frage die Ihr Gespr\u00e4chspartner hat zu beantworten.<\/p>\n<h2>2 \u2013 Nichts \u00fcber das Unternehmen wissen<\/h2>\n<p>Es mag Sie \u00fcberraschen, aber es kommt sehr h\u00e4ufig vor. Leute gehen zu Bewerbungsgespr\u00e4chen ohne eine Vorstellung von dem Gesch\u00e4ftsfeld des Unternehmens zu haben. In einigen F\u00e4llen ist es verst\u00e4ndlich, z.B. wenn Sie f\u00fcr ein Bewerbungsgespr\u00e4ch kontaktiert werden anstatt sich zu bewerben. Aber wenn Sie derjenige sind, der Interesse zeigen sollte, dann ergibt es keinen Sinn, das Sie nicht wissen was das Unternehmen tut.<br \/>\nBevor Sie zu einem Bewerbungsgespr\u00e4ch auf Franz\u00f6sisch gehen, sollten Sie immer \u00fcber das Unternehmen recherchieren. Benennen Sie das Tagesgesch\u00e4ft, den Markt, die Art der Produkte oder die Dienstleistungen, die sie verkaufen, wo sich Niederlassungen befinden (falle es ein gro\u00dfes Unternehmen mit vielen Standorten ist, dann k\u00f6nnen Sie sich einige von ihnen merken). Wenn Sie etwas Wissen \u00fcber das Unternehmen zum Ausdruck bringen, dann werden Sie engagierter wirken.<\/p>\n<h2>3 \u2013  Zu viel oder zu wenig w\u00e4hrend des Bewerbungsgespr\u00e4ches sprechen<\/h2>\n<p>Das Hauptziel in einem Bewerbungsgespr\u00e4ch auf Franz\u00f6sisch besteht darin sich selbst gegen\u00fcber dem Arbeitgeber zu verkaufen und zu einem anderen Grad zu beweisen, dass Ihr Franz\u00f6sisch f\u00fcr die Stelle gut genug ist. Daher sollten Sie sehr vorsichtig sein, welche Worte aus Ihrem Mund kommen, \u00fcbernehmen Sie sich nicht, m\u00f6glicherweise erw\u00e4hnen Sie etwas, das nicht so relevant ist oder Sie zeigen eine Schw\u00e4che, der Sie sich nicht bewusst sind.<br \/>\nBeantworten Sie jede Frage, die Ihnen gestellt wird, selbstsicher und lassen Sie Ihre K\u00f6rpersprache das Gesagte unterstreichen.<\/p>\n<p>Wenn Sie Ihren Erfolg in Ihrem n\u00e4chsten Bewerbungsgespr\u00e4ch auf Franz\u00f6sisch sicherstellen m\u00f6chten, dann sollten Sie einige Stunden bei uns nehmen! Hier bei Live-French.net haben wir <a href=\"https:\/\/live-french.net\/de\/franzosisch.php\/2007\/12\/26\/5-franzosischunterricht-unsere-lehrer\" title=\"nmuttersprachliche Franz\u00f6sischlehrer\">muttersprachliche Franz\u00f6sischlehrer<\/a>  die Ihnen helfen Ihr Franz\u00f6sisch f\u00fcr das Gesch\u00e4ftsleben zu verbessern!<\/p>\n<div id=\"media_image-2\" class=\"si-sidebar-widget si-widget si-entry widget widget_media_image amr_widget\"><h4 class=\"widget-title\">Perfectionnez votre fran\u00e7ais &#8211; cours d&#8217;essai gratuit! Inscrivez-vous ici<\/h4><a href=\"https:\/\/member.booknstart.com\/trial-registration?lg=fr&#038;referred_by=CTA&#038;office_id=6\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"366\" src=\"https:\/\/live-french.net\/wp-content\/uploads\/2025\/04\/CTA-LFNfr-1024x366.jpg\" class=\"image wp-image-27798  attachment-large size-large\" alt=\"\" style=\"max-width: 100%; height: auto;\" title=\"Perfectionnez votre fran\u00e7ais - cours d&#039;essai gratuit! Inscrivez-vous ici\" srcset=\"https:\/\/live-french.net\/wp-content\/uploads\/2025\/04\/CTA-LFNfr-1024x366.jpg 1024w, https:\/\/live-french.net\/wp-content\/uploads\/2025\/04\/CTA-LFNfr-300x107.jpg 300w, https:\/\/live-french.net\/wp-content\/uploads\/2025\/04\/CTA-LFNfr-768x274.jpg 768w, https:\/\/live-french.net\/wp-content\/uploads\/2025\/04\/CTA-LFNfr-1536x549.jpg 1536w, https:\/\/live-french.net\/wp-content\/uploads\/2025\/04\/CTA-LFNfr-2048x731.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Hier bei Live-French.net wissen wir wie schwierig es sein kann ein Bewerbungsgespr\u00e4ch auf Franz\u00f6sisch zu haben. Was auf anderen Sprachen passiert, das geschieht auch auf Franz\u00f6sisch, Bewerbungsgespr\u00e4che sind f\u00fcr jeden&hellip;<\/p>\n","protected":false},"author":5,"featured_media":24901,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[139],"tags":[],"class_list":["post-1538","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-business-franzoesisch"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fehler, die Sie in einem Bewerbungsgespr\u00e4ch auf Franz\u00f6sisch vermeiden sollten<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/live-french.net\/de\/blog\/business-franzoesisch\/bewerbungsgesprach-auf-franzosisch-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fehler, die Sie in einem Bewerbungsgespr\u00e4ch auf Franz\u00f6sisch vermeiden sollten\" \/>\n<meta property=\"og:description\" content=\"Hier bei Live-French.net wissen wir wie schwierig es sein kann ein Bewerbungsgespr\u00e4ch auf Franz\u00f6sisch zu haben. Was auf anderen Sprachen passiert, das geschieht auch auf Franz\u00f6sisch, Bewerbungsgespr\u00e4che sind f\u00fcr jeden&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/live-french.net\/de\/blog\/business-franzoesisch\/bewerbungsgesprach-auf-franzosisch-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Live French\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-30T22:00:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-20T12:18:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/live-french.net\/wp-content\/uploads\/2017\/10\/Bewerbungsgesprach-auf-Franzosisch.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2240\" \/>\n\t<meta property=\"og:image:height\" content=\"1260\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Live-French.net\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Live-French.net\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/blog\\\/business-franzoesisch\\\/bewerbungsgesprach-auf-franzosisch-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/blog\\\/business-franzoesisch\\\/bewerbungsgesprach-auf-franzosisch-2\\\/\"},\"author\":{\"name\":\"Live-French.net\",\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/#\\\/schema\\\/person\\\/f6352f8692c1c6f3f014d7fb5d9b40b7\"},\"headline\":\"Fehler, die Sie in einem Bewerbungsgespr\u00e4ch auf Franz\u00f6sisch vermeiden sollten\",\"datePublished\":\"2017-10-30T22:00:27+00:00\",\"dateModified\":\"2023-12-20T12:18:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/blog\\\/business-franzoesisch\\\/bewerbungsgesprach-auf-franzosisch-2\\\/\"},\"wordCount\":680,\"publisher\":{\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/blog\\\/business-franzoesisch\\\/bewerbungsgesprach-auf-franzosisch-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/live-french.net\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Bewerbungsgesprach-auf-Franzosisch.jpg\",\"articleSection\":[\"Business-Franz\u00f6sisch\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/blog\\\/business-franzoesisch\\\/bewerbungsgesprach-auf-franzosisch-2\\\/\",\"url\":\"https:\\\/\\\/live-french.net\\\/de\\\/blog\\\/business-franzoesisch\\\/bewerbungsgesprach-auf-franzosisch-2\\\/\",\"name\":\"Fehler, die Sie in einem Bewerbungsgespr\u00e4ch auf Franz\u00f6sisch vermeiden sollten\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/blog\\\/business-franzoesisch\\\/bewerbungsgesprach-auf-franzosisch-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/blog\\\/business-franzoesisch\\\/bewerbungsgesprach-auf-franzosisch-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/live-french.net\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Bewerbungsgesprach-auf-Franzosisch.jpg\",\"datePublished\":\"2017-10-30T22:00:27+00:00\",\"dateModified\":\"2023-12-20T12:18:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/blog\\\/business-franzoesisch\\\/bewerbungsgesprach-auf-franzosisch-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/live-french.net\\\/de\\\/blog\\\/business-franzoesisch\\\/bewerbungsgesprach-auf-franzosisch-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/blog\\\/business-franzoesisch\\\/bewerbungsgesprach-auf-franzosisch-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/live-french.net\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Bewerbungsgesprach-auf-Franzosisch.jpg\",\"contentUrl\":\"https:\\\/\\\/live-french.net\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Bewerbungsgesprach-auf-Franzosisch.jpg\",\"width\":2240,\"height\":1260},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/blog\\\/business-franzoesisch\\\/bewerbungsgesprach-auf-franzosisch-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/live-french.net\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fehler, die Sie in einem Bewerbungsgespr\u00e4ch auf Franz\u00f6sisch vermeiden sollten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/live-french.net\\\/de\\\/\",\"name\":\"Live French\",\"description\":\"Learn French Online\",\"publisher\":{\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/live-french.net\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/#organization\",\"name\":\"Live French\",\"url\":\"https:\\\/\\\/live-french.net\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/live-french.net\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/cropped-LiveFrenchLogo.png\",\"contentUrl\":\"https:\\\/\\\/live-french.net\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/cropped-LiveFrenchLogo.png\",\"width\":3319,\"height\":593,\"caption\":\"Live French\"},\"image\":{\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/#\\\/schema\\\/person\\\/f6352f8692c1c6f3f014d7fb5d9b40b7\",\"name\":\"Live-French.net\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0d950dad0e99393f15a738e9c0ee351d6f7e2bfef7629c657446dece0bc3ea9?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0d950dad0e99393f15a738e9c0ee351d6f7e2bfef7629c657446dece0bc3ea9?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0d950dad0e99393f15a738e9c0ee351d6f7e2bfef7629c657446dece0bc3ea9?s=96&d=blank&r=g\",\"caption\":\"Live-French.net\"},\"url\":\"https:\\\/\\\/live-french.net\\\/de\\\/blog\\\/author\\\/tania\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fehler, die Sie in einem Bewerbungsgespr\u00e4ch auf Franz\u00f6sisch vermeiden sollten","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/live-french.net\/de\/blog\/business-franzoesisch\/bewerbungsgesprach-auf-franzosisch-2\/","og_locale":"de_DE","og_type":"article","og_title":"Fehler, die Sie in einem Bewerbungsgespr\u00e4ch auf Franz\u00f6sisch vermeiden sollten","og_description":"Hier bei Live-French.net wissen wir wie schwierig es sein kann ein Bewerbungsgespr\u00e4ch auf Franz\u00f6sisch zu haben. Was auf anderen Sprachen passiert, das geschieht auch auf Franz\u00f6sisch, Bewerbungsgespr\u00e4che sind f\u00fcr jeden&hellip;","og_url":"https:\/\/live-french.net\/de\/blog\/business-franzoesisch\/bewerbungsgesprach-auf-franzosisch-2\/","og_site_name":"Live French","article_published_time":"2017-10-30T22:00:27+00:00","article_modified_time":"2023-12-20T12:18:21+00:00","og_image":[{"width":2240,"height":1260,"url":"https:\/\/live-french.net\/wp-content\/uploads\/2017\/10\/Bewerbungsgesprach-auf-Franzosisch.jpg","type":"image\/jpeg"}],"author":"Live-French.net","twitter_misc":{"Verfasst von":"Live-French.net","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/live-french.net\/de\/blog\/business-franzoesisch\/bewerbungsgesprach-auf-franzosisch-2\/#article","isPartOf":{"@id":"https:\/\/live-french.net\/de\/blog\/business-franzoesisch\/bewerbungsgesprach-auf-franzosisch-2\/"},"author":{"name":"Live-French.net","@id":"https:\/\/live-french.net\/de\/#\/schema\/person\/f6352f8692c1c6f3f014d7fb5d9b40b7"},"headline":"Fehler, die Sie in einem Bewerbungsgespr\u00e4ch auf Franz\u00f6sisch vermeiden sollten","datePublished":"2017-10-30T22:00:27+00:00","dateModified":"2023-12-20T12:18:21+00:00","mainEntityOfPage":{"@id":"https:\/\/live-french.net\/de\/blog\/business-franzoesisch\/bewerbungsgesprach-auf-franzosisch-2\/"},"wordCount":680,"publisher":{"@id":"https:\/\/live-french.net\/de\/#organization"},"image":{"@id":"https:\/\/live-french.net\/de\/blog\/business-franzoesisch\/bewerbungsgesprach-auf-franzosisch-2\/#primaryimage"},"thumbnailUrl":"https:\/\/live-french.net\/wp-content\/uploads\/2017\/10\/Bewerbungsgesprach-auf-Franzosisch.jpg","articleSection":["Business-Franz\u00f6sisch"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/live-french.net\/de\/blog\/business-franzoesisch\/bewerbungsgesprach-auf-franzosisch-2\/","url":"https:\/\/live-french.net\/de\/blog\/business-franzoesisch\/bewerbungsgesprach-auf-franzosisch-2\/","name":"Fehler, die Sie in einem Bewerbungsgespr\u00e4ch auf Franz\u00f6sisch vermeiden sollten","isPartOf":{"@id":"https:\/\/live-french.net\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/live-french.net\/de\/blog\/business-franzoesisch\/bewerbungsgesprach-auf-franzosisch-2\/#primaryimage"},"image":{"@id":"https:\/\/live-french.net\/de\/blog\/business-franzoesisch\/bewerbungsgesprach-auf-franzosisch-2\/#primaryimage"},"thumbnailUrl":"https:\/\/live-french.net\/wp-content\/uploads\/2017\/10\/Bewerbungsgesprach-auf-Franzosisch.jpg","datePublished":"2017-10-30T22:00:27+00:00","dateModified":"2023-12-20T12:18:21+00:00","breadcrumb":{"@id":"https:\/\/live-french.net\/de\/blog\/business-franzoesisch\/bewerbungsgesprach-auf-franzosisch-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/live-french.net\/de\/blog\/business-franzoesisch\/bewerbungsgesprach-auf-franzosisch-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/live-french.net\/de\/blog\/business-franzoesisch\/bewerbungsgesprach-auf-franzosisch-2\/#primaryimage","url":"https:\/\/live-french.net\/wp-content\/uploads\/2017\/10\/Bewerbungsgesprach-auf-Franzosisch.jpg","contentUrl":"https:\/\/live-french.net\/wp-content\/uploads\/2017\/10\/Bewerbungsgesprach-auf-Franzosisch.jpg","width":2240,"height":1260},{"@type":"BreadcrumbList","@id":"https:\/\/live-french.net\/de\/blog\/business-franzoesisch\/bewerbungsgesprach-auf-franzosisch-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/live-french.net\/de\/"},{"@type":"ListItem","position":2,"name":"Fehler, die Sie in einem Bewerbungsgespr\u00e4ch auf Franz\u00f6sisch vermeiden sollten"}]},{"@type":"WebSite","@id":"https:\/\/live-french.net\/de\/#website","url":"https:\/\/live-french.net\/de\/","name":"Live French","description":"Learn French Online","publisher":{"@id":"https:\/\/live-french.net\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/live-french.net\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/live-french.net\/de\/#organization","name":"Live French","url":"https:\/\/live-french.net\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/live-french.net\/de\/#\/schema\/logo\/image\/","url":"https:\/\/live-french.net\/wp-content\/uploads\/2021\/12\/cropped-LiveFrenchLogo.png","contentUrl":"https:\/\/live-french.net\/wp-content\/uploads\/2021\/12\/cropped-LiveFrenchLogo.png","width":3319,"height":593,"caption":"Live French"},"image":{"@id":"https:\/\/live-french.net\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/live-french.net\/de\/#\/schema\/person\/f6352f8692c1c6f3f014d7fb5d9b40b7","name":"Live-French.net","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/f0d950dad0e99393f15a738e9c0ee351d6f7e2bfef7629c657446dece0bc3ea9?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f0d950dad0e99393f15a738e9c0ee351d6f7e2bfef7629c657446dece0bc3ea9?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f0d950dad0e99393f15a738e9c0ee351d6f7e2bfef7629c657446dece0bc3ea9?s=96&d=blank&r=g","caption":"Live-French.net"},"url":"https:\/\/live-french.net\/de\/blog\/author\/tania\/"}]}},"_links":{"self":[{"href":"https:\/\/live-french.net\/de\/wp-json\/wp\/v2\/posts\/1538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/live-french.net\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/live-french.net\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/live-french.net\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/live-french.net\/de\/wp-json\/wp\/v2\/comments?post=1538"}],"version-history":[{"count":4,"href":"https:\/\/live-french.net\/de\/wp-json\/wp\/v2\/posts\/1538\/revisions"}],"predecessor-version":[{"id":24908,"href":"https:\/\/live-french.net\/de\/wp-json\/wp\/v2\/posts\/1538\/revisions\/24908"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/live-french.net\/de\/wp-json\/wp\/v2\/media\/24901"}],"wp:attachment":[{"href":"https:\/\/live-french.net\/de\/wp-json\/wp\/v2\/media?parent=1538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/live-french.net\/de\/wp-json\/wp\/v2\/categories?post=1538"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/live-french.net\/de\/wp-json\/wp\/v2\/tags?post=1538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}