{"id":1360,"date":"2017-09-17T21:24:08","date_gmt":"2017-09-17T19:24:08","guid":{"rendered":"https:\/\/live-french.net\/blog\/unkategorisiert\/die-grunde-weshalb-in-der-letzten-dekade-online-franzosischstunden-beliebter-als-lokale-franzosischstunden-geworden-sind\/"},"modified":"2023-12-29T13:52:54","modified_gmt":"2023-12-29T12:52:54","slug":"online-franzosischstunden","status":"publish","type":"post","link":"https:\/\/live-french.net\/de\/blog\/franzosisch-verbessern\/online-franzosischstunden\/","title":{"rendered":"Die Gr\u00fcnde weshalb in der letzten Dekade Online-Franz\u00f6sischstunden beliebter als lokale Franz\u00f6sischstunden geworden sind"},"content":{"rendered":"<p>Es ist Fakt, dass vor zehn bis 15 Jahren Online-Franz\u00f6sischstunden nicht so beliebt waren. Sie waren neu, die Leute waren skeptisch und die Technologie war nicht so gut, wie sie heute ist. Aber heute ist die Situation ganz anders. Online zu lernen ist der Standardweg des Lernens geworden, Breitbandinternetverbindungen sind weit verbreitet und Leute lernen mit gut etablierten Online-Schulen wie Live-French.net in qualitativ hochwertigen Franz\u00f6sischstunden.<\/p>\n<p>Auch wenn es bei Ihnen in der N\u00e4he Franz\u00f6sischstunden gibt, k\u00f6nnen Online-Stunden f\u00fcr Sie geeignet sein. Lassen Sie uns die Vor- und Nachteile beider Methoden durchgehen:<\/p>\n<h2>Franz\u00f6sischstunden in Ihrer N\u00e4he<\/h2>\n<p><strong>Vorteile:<\/strong><\/p>\n<ul>\n<li>Es kann eine gute Idee sein, wenn Sie Leute kennen lernen m\u00f6chten, mit denen Sie gemeinsame Interessen haben (zumindest m\u00f6chten sie auch Franz\u00f6sisch lernen)<\/li>\n<li>Klassenzimmer bieten manchmal Raum f\u00fcr Witze und zum Druck ablassen. Wenn es Ihnen gef\u00e4llt anderer Leute Meinung anzuh\u00f6ren und Ihre zu verbreiten, dann wird es Ihnen gefallen!<\/li>\n<li>Wenn der traditionelle Weg in der Schule bei Ihnen funktioniert hat, um Sprachen zu lernen, dann ist das m\u00f6glicherweise Ihre Methode. F\u00fcr die meisten  Leute funktioniert es nicht, aber bei einigen schon!<\/li>\n<\/ul>\n<p><strong>Nachteile:<\/strong><\/p>\n<ul>\n<li>Sie sind mit Sch\u00fclern zusammen, die m\u00f6glicherweise oder m\u00f6glicherweise nicht auf dem gleichen Niveau wie Sie sind. Und nicht alle zeigen das gleiche Engagement eine neue Sprache zu lernen.<\/li>\n<li>Auch wenn der Lehrer sehr gut unterrichtet bleibt es unm\u00f6glich mehr als f\u00fcnf Sch\u00fcler gleichzeitig zu begleiten und deren Schw\u00e4chen aufzuzeigen. <\/li>\n<li>If you have an unpredictable schedule, you have to keep in mind that you\u2019ll have to attend to classes probably more than once a week. <\/li>\n<\/ul>\n<div id=\"custom_html-26\" class=\"widget_text si-sidebar-widget si-widget si-entry widget widget_custom_html amr_widget\"><div class=\"textwidget custom-html-widget\"><a href=\"https:\/\/member.booknstart.com\/trial-registration?lg=fr&referred_by=sCTA&office_id=6\" target=\"_blank\"><img decoding=\"async\" alt=\"Cours d'essai de fran\u00e7ais\" src=\"https:\/\/live-french.net\/wp-content\/uploads\/2023\/02\/sCTA-fr.jpg\"><\/a><\/div><\/div>\n<h2>Franz\u00f6sischstunden online<\/h2>\n<p><strong>Vorteile:<\/strong><\/p>\n<ul>\n<li>Sie haben die ungeteilte Aufmerksamkeit Ihres Lehrers! Das wird Ihnen viel helfen an Ihren schw\u00e4chsten Punkten zu arbeiten und die Sprache schneller zu lernen.<\/li>\n<li>Sie k\u00f6nnen Stunden wann immer Sie m\u00f6chten besuchen. Sie k\u00f6nnen sie bequem von zu hause aus durchf\u00fchren, was Ihnen helfen wird Selbstbewusstsein zu entwickeln, weil Sie niemand anderes als Ihr Lehrer sieht\/h\u00f6rt. <\/li>\n<li>Sie m\u00fcssen mit niemanden Schritthalten, weil Sie der einzige Sch\u00fcler sind! Sie k\u00f6nnen Ihren Lehrer alle Fragen stellen und mit ihm \u00fcber alles sprechen was Sie m\u00f6chten, weil es keine Zeitvorgaben gibt.<\/li>\n<\/ul>\n<p><strong>Nachteile:<\/strong><\/p>\n<ul>\n<li>Sie werden keine anderen Sch\u00fcler kennenlernen, Sie werden keine weiteren Leute mit Ihren Interessen kennenlernen au\u00dfer Ihren Lehrer. Wenn einer Ihrer Motivationsgr\u00fcnde Franz\u00f6sisch zu lernen darin besteht neue Freunde zu finden, dann wird Online-Lernen nicht das Richtige f\u00fcr Sie sein.<\/li>\n<li>M\u00f6glicherweise gew\u00f6hnen Sie sich an den Akzent Ihres Lehrers wodurch es schwerer f\u00e4llt andere Leute zu verstehen.<\/li>\n<\/ul>\n<p>Sie werden ganz nach Ihren Zielen und nach Ihrer Pers\u00f6nlichkeit den besten Weg f\u00fcr sich w\u00e4hlen k\u00f6nnen. Auch wenn Online-Stunden sich als praktikable Methode erwiesen haben, die sich nach den Sch\u00fclern ausrichtet.<\/p>\n<p>Probieren Sie eine Online-Stunde mit einem unserer <a href=\"https:\/\/live-french.net\/de\/franzosisch.php\/2007\/12\/26\/5-franzosischunterricht-unsere-lehrer\" title=\"muttersprachlichen Franz\u00f6sischlehrer\">muttersprachlichen Franz\u00f6sischlehrer<\/a> aus und sehen Sie wie n\u00fctzlich diese Methode f\u00fcr Ihren Lernprozess sein kann!<\/p>\n<div id=\"media_image-2\" class=\"si-sidebar-widget si-widget si-entry widget widget_media_image amr_widget\"><h4 class=\"widget-title\">Perfectionnez votre fran\u00e7ais &#8211; cours d&#8217;essai gratuit! Inscrivez-vous ici<\/h4><a href=\"https:\/\/member.booknstart.com\/trial-registration?lg=fr&#038;referred_by=CTA&#038;office_id=6\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"366\" src=\"https:\/\/live-french.net\/wp-content\/uploads\/2025\/04\/CTA-LFNfr-1024x366.jpg\" class=\"image wp-image-27798  attachment-large size-large\" alt=\"\" style=\"max-width: 100%; height: auto;\" title=\"Perfectionnez votre fran\u00e7ais - cours d&#039;essai gratuit! Inscrivez-vous ici\" srcset=\"https:\/\/live-french.net\/wp-content\/uploads\/2025\/04\/CTA-LFNfr-1024x366.jpg 1024w, https:\/\/live-french.net\/wp-content\/uploads\/2025\/04\/CTA-LFNfr-300x107.jpg 300w, https:\/\/live-french.net\/wp-content\/uploads\/2025\/04\/CTA-LFNfr-768x274.jpg 768w, https:\/\/live-french.net\/wp-content\/uploads\/2025\/04\/CTA-LFNfr-1536x549.jpg 1536w, https:\/\/live-french.net\/wp-content\/uploads\/2025\/04\/CTA-LFNfr-2048x731.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Es ist Fakt, dass vor zehn bis 15 Jahren Online-Franz\u00f6sischstunden nicht so beliebt waren. Sie waren neu, die Leute waren skeptisch und die Technologie war nicht so gut, wie sie&hellip;<\/p>\n","protected":false},"author":1,"featured_media":25059,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[166],"tags":[],"class_list":["post-1360","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-franzosisch-verbessern"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Weshalb werden Online-Franz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/live-french.net\/de\/blog\/franzosisch-verbessern\/online-franzosischstunden\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Weshalb werden Online-Franz\" \/>\n<meta property=\"og:description\" content=\"Es ist Fakt, dass vor zehn bis 15 Jahren Online-Franz\u00f6sischstunden nicht so beliebt waren. Sie waren neu, die Leute waren skeptisch und die Technologie war nicht so gut, wie sie&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/live-french.net\/de\/blog\/franzosisch-verbessern\/online-franzosischstunden\/\" \/>\n<meta property=\"og:site_name\" content=\"Live French\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-17T19:24:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-29T12:52:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/live-french.net\/wp-content\/uploads\/2017\/09\/Online-Franzosischstunden.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2240\" \/>\n\t<meta property=\"og:image:height\" content=\"1260\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Live-French.net\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Live-French.net\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/blog\\\/franzosisch-verbessern\\\/online-franzosischstunden\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/blog\\\/franzosisch-verbessern\\\/online-franzosischstunden\\\/\"},\"author\":{\"name\":\"Live-French.net\",\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/#\\\/schema\\\/person\\\/f0cc22a1ee95a911e0b951bfcbd13e66\"},\"headline\":\"Die Gr\u00fcnde weshalb in der letzten Dekade Online-Franz\u00f6sischstunden beliebter als lokale Franz\u00f6sischstunden geworden sind\",\"datePublished\":\"2017-09-17T19:24:08+00:00\",\"dateModified\":\"2023-12-29T12:52:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/blog\\\/franzosisch-verbessern\\\/online-franzosischstunden\\\/\"},\"wordCount\":532,\"publisher\":{\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/blog\\\/franzosisch-verbessern\\\/online-franzosischstunden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/live-french.net\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/Online-Franzosischstunden.jpg\",\"articleSection\":[\"Verbessern Sie Ihr Sprachniveau\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/blog\\\/franzosisch-verbessern\\\/online-franzosischstunden\\\/\",\"url\":\"https:\\\/\\\/live-french.net\\\/de\\\/blog\\\/franzosisch-verbessern\\\/online-franzosischstunden\\\/\",\"name\":\"Weshalb werden Online-Franz\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/blog\\\/franzosisch-verbessern\\\/online-franzosischstunden\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/blog\\\/franzosisch-verbessern\\\/online-franzosischstunden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/live-french.net\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/Online-Franzosischstunden.jpg\",\"datePublished\":\"2017-09-17T19:24:08+00:00\",\"dateModified\":\"2023-12-29T12:52:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/blog\\\/franzosisch-verbessern\\\/online-franzosischstunden\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/live-french.net\\\/de\\\/blog\\\/franzosisch-verbessern\\\/online-franzosischstunden\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/blog\\\/franzosisch-verbessern\\\/online-franzosischstunden\\\/#primaryimage\",\"url\":\"https:\\\/\\\/live-french.net\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/Online-Franzosischstunden.jpg\",\"contentUrl\":\"https:\\\/\\\/live-french.net\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/Online-Franzosischstunden.jpg\",\"width\":2240,\"height\":1260},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/blog\\\/franzosisch-verbessern\\\/online-franzosischstunden\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/live-french.net\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Gr\u00fcnde weshalb in der letzten Dekade Online-Franz\u00f6sischstunden beliebter als lokale Franz\u00f6sischstunden geworden sind\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/live-french.net\\\/de\\\/\",\"name\":\"Live French\",\"description\":\"Learn French Online\",\"publisher\":{\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/live-french.net\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/#organization\",\"name\":\"Live French\",\"url\":\"https:\\\/\\\/live-french.net\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/live-french.net\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/cropped-LiveFrenchLogo.png\",\"contentUrl\":\"https:\\\/\\\/live-french.net\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/cropped-LiveFrenchLogo.png\",\"width\":3319,\"height\":593,\"caption\":\"Live French\"},\"image\":{\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/#\\\/schema\\\/person\\\/f0cc22a1ee95a911e0b951bfcbd13e66\",\"name\":\"Live-French.net\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8e35468b76810985304ee610be12be3ea6deea89263c877a3343da105d61bde8?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8e35468b76810985304ee610be12be3ea6deea89263c877a3343da105d61bde8?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8e35468b76810985304ee610be12be3ea6deea89263c877a3343da105d61bde8?s=96&d=blank&r=g\",\"caption\":\"Live-French.net\"},\"description\":\"Thanks for visiting our blog! Go a step further and see how we can help you improve your French and register for a FREE trial lesson by Zoom with one of our online French teachers.\",\"sameAs\":[\"https:\\\/\\\/live-french.net\"],\"url\":\"https:\\\/\\\/live-french.net\\\/de\\\/blog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Weshalb werden Online-Franz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/live-french.net\/de\/blog\/franzosisch-verbessern\/online-franzosischstunden\/","og_locale":"de_DE","og_type":"article","og_title":"Weshalb werden Online-Franz","og_description":"Es ist Fakt, dass vor zehn bis 15 Jahren Online-Franz\u00f6sischstunden nicht so beliebt waren. Sie waren neu, die Leute waren skeptisch und die Technologie war nicht so gut, wie sie&hellip;","og_url":"https:\/\/live-french.net\/de\/blog\/franzosisch-verbessern\/online-franzosischstunden\/","og_site_name":"Live French","article_published_time":"2017-09-17T19:24:08+00:00","article_modified_time":"2023-12-29T12:52:54+00:00","og_image":[{"width":2240,"height":1260,"url":"https:\/\/live-french.net\/wp-content\/uploads\/2017\/09\/Online-Franzosischstunden.jpg","type":"image\/jpeg"}],"author":"Live-French.net","twitter_misc":{"Verfasst von":"Live-French.net","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/live-french.net\/de\/blog\/franzosisch-verbessern\/online-franzosischstunden\/#article","isPartOf":{"@id":"https:\/\/live-french.net\/de\/blog\/franzosisch-verbessern\/online-franzosischstunden\/"},"author":{"name":"Live-French.net","@id":"https:\/\/live-french.net\/de\/#\/schema\/person\/f0cc22a1ee95a911e0b951bfcbd13e66"},"headline":"Die Gr\u00fcnde weshalb in der letzten Dekade Online-Franz\u00f6sischstunden beliebter als lokale Franz\u00f6sischstunden geworden sind","datePublished":"2017-09-17T19:24:08+00:00","dateModified":"2023-12-29T12:52:54+00:00","mainEntityOfPage":{"@id":"https:\/\/live-french.net\/de\/blog\/franzosisch-verbessern\/online-franzosischstunden\/"},"wordCount":532,"publisher":{"@id":"https:\/\/live-french.net\/de\/#organization"},"image":{"@id":"https:\/\/live-french.net\/de\/blog\/franzosisch-verbessern\/online-franzosischstunden\/#primaryimage"},"thumbnailUrl":"https:\/\/live-french.net\/wp-content\/uploads\/2017\/09\/Online-Franzosischstunden.jpg","articleSection":["Verbessern Sie Ihr Sprachniveau"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/live-french.net\/de\/blog\/franzosisch-verbessern\/online-franzosischstunden\/","url":"https:\/\/live-french.net\/de\/blog\/franzosisch-verbessern\/online-franzosischstunden\/","name":"Weshalb werden Online-Franz","isPartOf":{"@id":"https:\/\/live-french.net\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/live-french.net\/de\/blog\/franzosisch-verbessern\/online-franzosischstunden\/#primaryimage"},"image":{"@id":"https:\/\/live-french.net\/de\/blog\/franzosisch-verbessern\/online-franzosischstunden\/#primaryimage"},"thumbnailUrl":"https:\/\/live-french.net\/wp-content\/uploads\/2017\/09\/Online-Franzosischstunden.jpg","datePublished":"2017-09-17T19:24:08+00:00","dateModified":"2023-12-29T12:52:54+00:00","breadcrumb":{"@id":"https:\/\/live-french.net\/de\/blog\/franzosisch-verbessern\/online-franzosischstunden\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/live-french.net\/de\/blog\/franzosisch-verbessern\/online-franzosischstunden\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/live-french.net\/de\/blog\/franzosisch-verbessern\/online-franzosischstunden\/#primaryimage","url":"https:\/\/live-french.net\/wp-content\/uploads\/2017\/09\/Online-Franzosischstunden.jpg","contentUrl":"https:\/\/live-french.net\/wp-content\/uploads\/2017\/09\/Online-Franzosischstunden.jpg","width":2240,"height":1260},{"@type":"BreadcrumbList","@id":"https:\/\/live-french.net\/de\/blog\/franzosisch-verbessern\/online-franzosischstunden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/live-french.net\/de\/"},{"@type":"ListItem","position":2,"name":"Die Gr\u00fcnde weshalb in der letzten Dekade Online-Franz\u00f6sischstunden beliebter als lokale Franz\u00f6sischstunden geworden sind"}]},{"@type":"WebSite","@id":"https:\/\/live-french.net\/de\/#website","url":"https:\/\/live-french.net\/de\/","name":"Live French","description":"Learn French Online","publisher":{"@id":"https:\/\/live-french.net\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/live-french.net\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/live-french.net\/de\/#organization","name":"Live French","url":"https:\/\/live-french.net\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/live-french.net\/de\/#\/schema\/logo\/image\/","url":"https:\/\/live-french.net\/wp-content\/uploads\/2021\/12\/cropped-LiveFrenchLogo.png","contentUrl":"https:\/\/live-french.net\/wp-content\/uploads\/2021\/12\/cropped-LiveFrenchLogo.png","width":3319,"height":593,"caption":"Live French"},"image":{"@id":"https:\/\/live-french.net\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/live-french.net\/de\/#\/schema\/person\/f0cc22a1ee95a911e0b951bfcbd13e66","name":"Live-French.net","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/8e35468b76810985304ee610be12be3ea6deea89263c877a3343da105d61bde8?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8e35468b76810985304ee610be12be3ea6deea89263c877a3343da105d61bde8?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8e35468b76810985304ee610be12be3ea6deea89263c877a3343da105d61bde8?s=96&d=blank&r=g","caption":"Live-French.net"},"description":"Thanks for visiting our blog! Go a step further and see how we can help you improve your French and register for a FREE trial lesson by Zoom with one of our online French teachers.","sameAs":["https:\/\/live-french.net"],"url":"https:\/\/live-french.net\/de\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/live-french.net\/de\/wp-json\/wp\/v2\/posts\/1360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/live-french.net\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/live-french.net\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/live-french.net\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/live-french.net\/de\/wp-json\/wp\/v2\/comments?post=1360"}],"version-history":[{"count":8,"href":"https:\/\/live-french.net\/de\/wp-json\/wp\/v2\/posts\/1360\/revisions"}],"predecessor-version":[{"id":25067,"href":"https:\/\/live-french.net\/de\/wp-json\/wp\/v2\/posts\/1360\/revisions\/25067"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/live-french.net\/de\/wp-json\/wp\/v2\/media\/25059"}],"wp:attachment":[{"href":"https:\/\/live-french.net\/de\/wp-json\/wp\/v2\/media?parent=1360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/live-french.net\/de\/wp-json\/wp\/v2\/categories?post=1360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/live-french.net\/de\/wp-json\/wp\/v2\/tags?post=1360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}