{"id":128,"count":0,"description":"","link":"https:\/\/live-french.net\/de\/blog\/category\/unkategorisiert\/","name":"Unkategorisiert","slug":"unkategorisiert","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Unkategorisiert Archives | Live French<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/live-french.net\/de\/blog\/category\/unkategorisiert\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unkategorisiert Archives | Live French\" \/>\n<meta property=\"og:url\" content=\"https:\/\/live-french.net\/de\/blog\/category\/unkategorisiert\/\" \/>\n<meta property=\"og:site_name\" content=\"Live French\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/blog\\\/category\\\/unkategorisiert\\\/\",\"url\":\"https:\\\/\\\/live-french.net\\\/de\\\/blog\\\/category\\\/unkategorisiert\\\/\",\"name\":\"Unkategorisiert Archives | Live French\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/blog\\\/category\\\/unkategorisiert\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/blog\\\/category\\\/unkategorisiert\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/live-french.net\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unkategorisiert\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/live-french.net\\\/de\\\/\",\"name\":\"Live French\",\"description\":\"Learn French Online\",\"publisher\":{\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/live-french.net\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/#organization\",\"name\":\"Live French\",\"url\":\"https:\\\/\\\/live-french.net\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/live-french.net\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/cropped-LiveFrenchLogo.png\",\"contentUrl\":\"https:\\\/\\\/live-french.net\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/cropped-LiveFrenchLogo.png\",\"width\":3319,\"height\":593,\"caption\":\"Live French\"},\"image\":{\"@id\":\"https:\\\/\\\/live-french.net\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unkategorisiert Archives | Live French","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/live-french.net\/de\/blog\/category\/unkategorisiert\/","og_locale":"de_DE","og_type":"article","og_title":"Unkategorisiert Archives | Live French","og_url":"https:\/\/live-french.net\/de\/blog\/category\/unkategorisiert\/","og_site_name":"Live French","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/live-french.net\/de\/blog\/category\/unkategorisiert\/","url":"https:\/\/live-french.net\/de\/blog\/category\/unkategorisiert\/","name":"Unkategorisiert Archives | Live French","isPartOf":{"@id":"https:\/\/live-french.net\/de\/#website"},"breadcrumb":{"@id":"https:\/\/live-french.net\/de\/blog\/category\/unkategorisiert\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/live-french.net\/de\/blog\/category\/unkategorisiert\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/live-french.net\/de\/"},{"@type":"ListItem","position":2,"name":"Unkategorisiert"}]},{"@type":"WebSite","@id":"https:\/\/live-french.net\/de\/#website","url":"https:\/\/live-french.net\/de\/","name":"Live French","description":"Learn French Online","publisher":{"@id":"https:\/\/live-french.net\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/live-french.net\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/live-french.net\/de\/#organization","name":"Live French","url":"https:\/\/live-french.net\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/live-french.net\/de\/#\/schema\/logo\/image\/","url":"https:\/\/live-french.net\/wp-content\/uploads\/2021\/12\/cropped-LiveFrenchLogo.png","contentUrl":"https:\/\/live-french.net\/wp-content\/uploads\/2021\/12\/cropped-LiveFrenchLogo.png","width":3319,"height":593,"caption":"Live French"},"image":{"@id":"https:\/\/live-french.net\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/live-french.net\/de\/wp-json\/wp\/v2\/categories\/128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/live-french.net\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/live-french.net\/de\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/live-french.net\/de\/wp-json\/wp\/v2\/posts?categories=128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}